{"id":9959,"date":"2024-04-17T13:00:57","date_gmt":"2024-04-17T11:00:57","guid":{"rendered":"https:\/\/lafarinadicuneo.it\/prodotto\/farina-di-castagne\/"},"modified":"2026-05-13T12:02:13","modified_gmt":"2026-05-13T10:02:13","slug":"farina-di-castagne","status":"publish","type":"product","link":"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/","title":{"rendered":"Farina di castagne"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e6231e&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;8%&#8221; top_padding_tablet=&#8221;14%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;14%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;home&#8221; disable_element=&#8221;yes&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;right&#8221; column_element_spacing=&#8221;10px&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; zindex=&#8221;100&#8243; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_t_to_right_b&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12 vc_hidden-xs&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;10&#8243; top_padding_tablet=&#8221;8%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h5>LA FARINA CHE FA PER TE<\/h5>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Ad ognuno la propria miscela e il proprio formato&#8221;][\/split_line_heading][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;5px&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text]Che tu sia un consumatore appassionato e desideroso di impastare o un&#8217;impresa attenta alla selezione delle materie prime, grazie alla conoscenza e l&#8217;esperienza tramandata da generazioni, La farina di Cuneo offre una gamma di prodotti di altissima qualit\u00e0 insieme a servizi personalizzati sia nell\u2019ambito della consegna che nel post vendita.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;90px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; top_padding_tablet=&#8221;0&#8243; top_padding_phone=&#8221;0&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;20&#8243; bottom_margin=&#8221;20&#8243; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;small_desktop&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-lg-6 vc_col-md-12&#8243;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1665387946515{margin-bottom: 10px !important;}&#8221;]\n<h4>A casa<\/h4>\n[\/vc_column_text][vc_column_text]Farina per ogni destinazione d\u2019uso pensata per poter sviluppare quotidianamente prodotti sani e genuini.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;20&#8243; bottom_margin=&#8221;20&#8243; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;small_desktop&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-lg-6 vc_col-md-12&#8243;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1665387969220{margin-bottom: 10px !important;}&#8221;]\n<h4>Per uso professionale<\/h4>\n[\/vc_column_text][vc_column_text]Miscele professionali e sviluppate ad hoc adatte alla lavorazione dell\u2019arte bianca o nei differenti settori di produzione alimentare.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][nectar_cascading_images image_1_bg_color=&#8221;#ffffff&#8221; image_1_offset_x_sign=&#8221;+&#8221; image_1_offset_x=&#8221;0%&#8221; image_1_offset_y_sign=&#8221;+&#8221; image_1_offset_y=&#8221;20%&#8221; image_1_rotate_sign=&#8221;+&#8221; image_1_rotate=&#8221;none&#8221; image_1_scale=&#8221;1&#8243; image_1_padding=&#8221;auto&#8221; image_1_box_shadow=&#8221;none&#8221; image_1_max_width_desktop=&#8221;100%&#8221; image_1_max_width_mobile=&#8221;100%&#8221; image_1_image_width_mobile=&#8221;default&#8221; image_2_url=&#8221;7062&#8243; image_2_offset_x_sign=&#8221;+&#8221; image_2_offset_x=&#8221;0%&#8221; image_2_offset_y_sign=&#8221;+&#8221; image_2_offset_y=&#8221;0%&#8221; image_2_rotate_sign=&#8221;+&#8221; image_2_rotate=&#8221;none&#8221; image_2_scale=&#8221;1&#8243; image_2_padding=&#8221;auto&#8221; image_2_box_shadow=&#8221;none&#8221; image_2_max_width_desktop=&#8221;100%&#8221; image_2_max_width_mobile=&#8221;100%&#8221; image_2_image_width_mobile=&#8221;default&#8221; image_3_offset_x_sign=&#8221;+&#8221; image_3_offset_x=&#8221;0%&#8221; image_3_offset_y_sign=&#8221;+&#8221; image_3_offset_y=&#8221;0%&#8221; image_3_rotate_sign=&#8221;+&#8221; image_3_rotate=&#8221;none&#8221; image_3_scale=&#8221;1&#8243; image_3_padding=&#8221;auto&#8221; image_3_box_shadow=&#8221;none&#8221; image_3_max_width_desktop=&#8221;100%&#8221; image_3_max_width_mobile=&#8221;100%&#8221; image_3_image_width_mobile=&#8221;default&#8221; image_4_offset_x_sign=&#8221;+&#8221; image_4_offset_x=&#8221;0%&#8221; image_4_offset_y_sign=&#8221;+&#8221; image_4_offset_y=&#8221;0%&#8221; image_4_rotate_sign=&#8221;+&#8221; image_4_rotate=&#8221;none&#8221; image_4_scale=&#8221;1&#8243; image_4_padding=&#8221;auto&#8221; image_4_box_shadow=&#8221;none&#8221; image_4_max_width_desktop=&#8221;100%&#8221; image_4_max_width_mobile=&#8221;100%&#8221; image_4_image_width_mobile=&#8221;default&#8221; element_sizing=&#8221;forced&#8221; element_sizing_aspect=&#8221;4-3&#8243; image_loading=&#8221;default&#8221; border_radius=&#8221;none&#8221; parallax_scrolling=&#8221;yes&#8221; layer_1_parallax_scrolling=&#8221;no&#8221; parallax_scrolling_intensity=&#8221;subtle&#8221; overflow=&#8221;hidden&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Farina composta al 100% da castagne della variet\u00e0 locale Garrone rosso biologiche, essiccate e macinate a pietra come da tradizione. Un prodotto versatile adatto alla preparazione di ricette sia dolci che salate, in grado di riportarti indietro nel tempo ai sapori \u201cdi una volta\u201d. Privo di note amare e naturalmente senza glutine.<\/p>\n<p>Qt. 500g<\/p>\n","protected":false},"featured_media":8372,"template":"","meta":[],"product_cat":[108,118,71],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Farina di castagne - Farina di Cuneo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Farina di castagne - Farina di Cuneo\" \/>\n<meta property=\"og:description\" content=\"Farina composta al 100% da castagne della variet\u00e0 locale Garrone rosso biologiche, essiccate e macinate a pietra come da tradizione. Un prodotto versatile adatto alla preparazione di ricette sia dolci che salate, in grado di riportarti indietro nel tempo ai sapori \u201cdi una volta\u201d. Privo di note amare e naturalmente senza glutine.  Qt. 500g\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/\" \/>\n<meta property=\"og:site_name\" content=\"Farina di Cuneo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lafarinadicuneo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:02:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lafarinadicuneo.it\/wp-content\/uploads\/2024\/04\/farina_castagne_verticale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/\",\"url\":\"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/\",\"name\":\"Farina di castagne - Farina di Cuneo\",\"isPartOf\":{\"@id\":\"https:\/\/lafarinadicuneo.it\/en\/#website\"},\"datePublished\":\"2024-04-17T11:00:57+00:00\",\"dateModified\":\"2026-05-13T10:02:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lafarinadicuneo.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/lafarinadicuneo.it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Farina di castagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lafarinadicuneo.it\/en\/#website\",\"url\":\"https:\/\/lafarinadicuneo.it\/en\/\",\"name\":\"Farina di Cuneo\",\"description\":\"Sinonimo di eccellenza e autenticita\u0300, grazie all\u2019utilizzo di grani teneri 100% Italiani di alta qualita\u0300 a provenienza certificata.\",\"publisher\":{\"@id\":\"https:\/\/lafarinadicuneo.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lafarinadicuneo.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lafarinadicuneo.it\/en\/#organization\",\"name\":\"Farina di Cuneo\",\"url\":\"https:\/\/lafarinadicuneo.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lafarinadicuneo.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lafarinadicuneo.it\/wp-content\/uploads\/2022\/07\/logo-FdC-mob.png\",\"contentUrl\":\"https:\/\/lafarinadicuneo.it\/wp-content\/uploads\/2022\/07\/logo-FdC-mob.png\",\"width\":297,\"height\":211,\"caption\":\"Farina di Cuneo\"},\"image\":{\"@id\":\"https:\/\/lafarinadicuneo.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/lafarinadicuneo\/\",\"https:\/\/www.facebook.com\/lafarinadicuneo\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"10.80\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farina di castagne - Farina di Cuneo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/","og_locale":"en_US","og_type":"article","og_title":"Farina di castagne - Farina di Cuneo","og_description":"Farina composta al 100% da castagne della variet\u00e0 locale Garrone rosso biologiche, essiccate e macinate a pietra come da tradizione. Un prodotto versatile adatto alla preparazione di ricette sia dolci che salate, in grado di riportarti indietro nel tempo ai sapori \u201cdi una volta\u201d. Privo di note amare e naturalmente senza glutine.  Qt. 500g","og_url":"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/","og_site_name":"Farina di Cuneo","article_publisher":"https:\/\/www.facebook.com\/lafarinadicuneo","article_modified_time":"2026-05-13T10:02:13+00:00","og_image":[{"width":2560,"height":2048,"url":"https:\/\/lafarinadicuneo.it\/wp-content\/uploads\/2024\/04\/farina_castagne_verticale.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/","url":"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/","name":"Farina di castagne - Farina di Cuneo","isPartOf":{"@id":"https:\/\/lafarinadicuneo.it\/en\/#website"},"datePublished":"2024-04-17T11:00:57+00:00","dateModified":"2026-05-13T10:02:13+00:00","breadcrumb":{"@id":"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lafarinadicuneo.it\/en\/prodotto\/farina-di-castagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lafarinadicuneo.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lafarinadicuneo.it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Farina di castagne"}]},{"@type":"WebSite","@id":"https:\/\/lafarinadicuneo.it\/en\/#website","url":"https:\/\/lafarinadicuneo.it\/en\/","name":"Farina di Cuneo","description":"Sinonimo di eccellenza e autenticita\u0300, grazie all\u2019utilizzo di grani teneri 100% Italiani di alta qualita\u0300 a provenienza certificata.","publisher":{"@id":"https:\/\/lafarinadicuneo.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lafarinadicuneo.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lafarinadicuneo.it\/en\/#organization","name":"Farina di Cuneo","url":"https:\/\/lafarinadicuneo.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lafarinadicuneo.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lafarinadicuneo.it\/wp-content\/uploads\/2022\/07\/logo-FdC-mob.png","contentUrl":"https:\/\/lafarinadicuneo.it\/wp-content\/uploads\/2022\/07\/logo-FdC-mob.png","width":297,"height":211,"caption":"Farina di Cuneo"},"image":{"@id":"https:\/\/lafarinadicuneo.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lafarinadicuneo\/","https:\/\/www.facebook.com\/lafarinadicuneo"]}]},"product_price_amount":"10.80","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/lafarinadicuneo.it\/en\/wp-json\/wp\/v2\/product\/9959"}],"collection":[{"href":"https:\/\/lafarinadicuneo.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lafarinadicuneo.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lafarinadicuneo.it\/en\/wp-json\/wp\/v2\/media\/8372"}],"wp:attachment":[{"href":"https:\/\/lafarinadicuneo.it\/en\/wp-json\/wp\/v2\/media?parent=9959"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lafarinadicuneo.it\/en\/wp-json\/wp\/v2\/product_cat?post=9959"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lafarinadicuneo.it\/en\/wp-json\/wp\/v2\/product_tag?post=9959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}